{"id":15703,"date":"2014-05-22T11:21:26","date_gmt":"2014-05-22T14:21:26","guid":{"rendered":"http:\/\/bestradiobrasil.com\/br\/?p=15703"},"modified":"2014-05-22T11:21:26","modified_gmt":"2014-05-22T14:21:26","slug":"miley-cyrus-aterriza-no-brasil-em-setembro","status":"publish","type":"post","link":"https:\/\/bestradiobrasil.com\/br\/miley-cyrus-aterriza-no-brasil-em-setembro\/","title":{"rendered":"Miley Cyrus aterriza no Brasil em setembro"},"content":{"rendered":"<p>A cantora j\u00e1 havia divulgado que viria para a Am\u00e9rica do Sul, mas agora \u00e9 oficial a passagem de <strong>Miley Cyrus<\/strong> pelo<strong> Brasil<\/strong> para s\u00e9rie de shows.<\/p>\n<p><!--more--><\/p>\n<p>Ainda n\u00e3o foram especificados datas dos shows da <strong>Bangerz Tour<\/strong> e pre\u00e7os dos ingressos.<\/p>\n<p><strong>Miley Cyrus<\/strong> est\u00e1 rodando o mundo e at\u00e9 o momento j\u00e1 possui 64 show agendados. Recentemente, a cantora teve algumas apresenta\u00e7\u00f5es canceladas devido a problemas de sa\u00fade, mas j\u00e1 est\u00e1 na estrada novamente pela Europa.<\/p>\n<p>A pop j\u00e1 esteve no Brasil em 2011 para com shows da <strong>Gypsy Heart Tour<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cantora j\u00e1 havia divulgado que viria para a Am\u00e9rica do Sul, mas agora \u00e9 oficial a passagem de Miley Cyrus pelo Brasil para s\u00e9rie de shows.<\/p>\n","protected":false},"author":6,"featured_media":15704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","webixso_pending_account_ids":""},"categories":[1],"tags":[4897,1247,4898,664],"class_list":["post-15703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-da-musica","tag-bangerz-tour","tag-brasil","tag-gypsy-heart-tour","tag-miley-cyrus"],"_links":{"self":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/15703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/comments?post=15703"}],"version-history":[{"count":0,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/15703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media\/15704"}],"wp:attachment":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media?parent=15703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/categories?post=15703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/tags?post=15703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}