{"id":19546,"date":"2014-12-08T18:45:41","date_gmt":"2014-12-08T20:45:41","guid":{"rendered":"http:\/\/bestradiobrasil.com\/br\/?p=19546"},"modified":"2014-12-08T15:54:38","modified_gmt":"2014-12-08T17:54:38","slug":"miley-cyrus-apresenta-musica-inedita-twinkle-song","status":"publish","type":"post","link":"https:\/\/bestradiobrasil.com\/br\/miley-cyrus-apresenta-musica-inedita-twinkle-song\/","title":{"rendered":"Miley Cyrus apresenta a m\u00fasica in\u00e9dita The Twinkle Song"},"content":{"rendered":"<p><strong>Miley Cyrus<\/strong> apresentou aos f\u00e3s em um show na \u00faltima semana a m\u00fasica <em>The Twinkle Song<\/em>, inspirada na morte de um gato que pertencia a uma amiga pr\u00f3xima.<\/p>\n<blockquote><p>&#8220;Eu me senti como se o gato me dissesse o que eu deveria fazer para que minha amiga superasse a situa\u00e7\u00e3o&#8230; Foi mais terapia do que qualquer coisa, explicou Miley.<\/p><\/blockquote>\n<p>A cantora contou ainda ter sonhado com o bichinho. Assista \u00e0 performance de <em>The Twinkle Song<\/em>:<\/p>\n<p>[youtube]https:\/\/www.youtube.com\/watch?v=0Am2m13XN3E[\/youtube]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miley Cyrus apresentou aos f\u00e3s em um show na \u00faltima semana a m\u00fasica The Twinkle Song, inspirada na morte de um gato que pertencia a uma amiga pr\u00f3xima. &#8220;Eu me senti como se o gato me dissesse o que eu deveria fazer para que minha amiga superasse a situa\u00e7\u00e3o&#8230; Foi mais terapia do que qualquer [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":19547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","webixso_pending_account_ids":""},"categories":[1],"tags":[8261,8264,664,8262,8263,8260],"class_list":["post-19546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-da-musica","tag-gato","tag-inspiracao","tag-miley-cyrus","tag-morte-de-um-gato","tag-sonho","tag-the-twinkle-song"],"_links":{"self":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/19546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/comments?post=19546"}],"version-history":[{"count":0,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/19546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media\/19547"}],"wp:attachment":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media?parent=19546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/categories?post=19546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/tags?post=19546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}