{"id":23606,"date":"2017-01-24T16:41:08","date_gmt":"2017-01-24T18:41:08","guid":{"rendered":"http:\/\/bestradiobrasil.com\/br\/?p=23606"},"modified":"2017-01-24T16:41:08","modified_gmt":"2017-01-24T18:41:08","slug":"slipknot-divulgou-o-video-de-killpop-gravado-por-fas","status":"publish","type":"post","link":"https:\/\/bestradiobrasil.com\/br\/slipknot-divulgou-o-video-de-killpop-gravado-por-fas\/","title":{"rendered":"Slipknot divulgou o v\u00eddeo de Killpop gravado por f\u00e3s"},"content":{"rendered":"<p>Os mascarados do <strong>Slipknot<\/strong> apresentaram o v\u00eddeo da apresenta\u00e7\u00e3o ao vivo de <em>Killpop<\/em> gravada por\u00a0f\u00e3s.<\/p>\n<p>A banda pediu para os f\u00e3s filmarem o show pelo seu ponto de vista. O evento aconteceu em 19 de\u00a0agosto de 2015, no <strong>Red Rocks<\/strong>, em Morrison, Colorado.<\/p>\n<p>A m\u00fasica\u00a0\u00e9 parte do quinto \u00e1lbum de est\u00fadio do grupo <strong>.5: The Gray Chapter<\/strong>, lan\u00e7ado em outubro\u00a0de 2014. O material j\u00e1 inclui os singles <em>The Devil In I<\/em>, <em>Custer<\/em> e <em>Xix<\/em>.<\/p>\n<p>Confira o v\u00eddeo abaixo:<\/p>\n<p><iframe title=\"Slipknot - &quot;Killpop&quot; Live at Red Rocks (Fan Footage)\" width=\"620\" height=\"349\" src=\"https:\/\/www.youtube.com\/embed\/xzCf4Gn0oFE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os mascarados do Slipknot apresentaram o v\u00eddeo da apresenta\u00e7\u00e3o ao vivo de Killpop gravada por\u00a0f\u00e3s. A banda pediu para os f\u00e3s filmarem o show pelo seu ponto de vista. O evento aconteceu em 19 de\u00a0agosto de 2015, no Red Rocks, em Morrison, Colorado. A m\u00fasica\u00a0\u00e9 parte do quinto \u00e1lbum de est\u00fadio do grupo .5: The [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":23607,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","webixso_pending_account_ids":""},"categories":[5],"tags":[6568,11168,1368,6567,11169],"class_list":["post-23606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos","tag-5-the-gray-chapter","tag-custer","tag-slipknot","tag-the-devil-in-i","tag-xix"],"_links":{"self":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/23606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/comments?post=23606"}],"version-history":[{"count":0,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/23606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media\/23607"}],"wp:attachment":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media?parent=23606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/categories?post=23606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/tags?post=23606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}