{"id":2604,"date":"2009-07-02T13:11:15","date_gmt":"2009-07-02T16:11:15","guid":{"rendered":"http:\/\/www.bestradiobrasil.com\/br\/?p=2604"},"modified":"2009-07-03T10:02:10","modified_gmt":"2009-07-03T13:02:10","slug":"mamomas-assassinas-revivem-no-cinema","status":"publish","type":"post","link":"https:\/\/bestradiobrasil.com\/br\/mamomas-assassinas-revivem-no-cinema\/","title":{"rendered":"Mamomas Assassinas revivem no cinema"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-2605\" title=\"mamonas\" src=\"http:\/\/www.bestradiobrasil.com\/br\/wp-content\/uploads\/2009\/07\/mamonas.jpg\" alt=\"mamonas\" width=\"445\" height=\"131\" srcset=\"https:\/\/bestradiobrasil.com\/br\/wp-content\/uploads\/2009\/07\/mamonas.jpg 445w, https:\/\/bestradiobrasil.com\/br\/wp-content\/uploads\/2009\/07\/mamonas-300x88.jpg 300w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/><\/p>\n<p>Eles tiveram uma carreira curta que acabou tragicamente em um acidente de avi\u00e3o que matou todos os membros da banda em 1996, mas n\u00e3o se pode negar que fizeram sucesso.<\/p>\n<p>O <strong>Mamonas Assassinas<\/strong> vendeu mais de dois milh\u00f5es de discos em seis meses e certamente deixaram o Brasil todo com gosto de quero mais&#8230;<\/p>\n<p>Para matar a saudade e relembrar a alegria da banda, foi filmado o document\u00e1rio &#8220;<strong>Mamonas, o Doc<\/strong>&#8220;, dirigido por <strong>Cl\u00e1udio Kahns<\/strong> (de &#8220;<strong>Feliz Ano Velho<\/strong>&#8221; e &#8220;<strong>A Marvada Carne<\/strong>&#8220;).<\/p>\n<p>O filme de 84 minutos conta com imagens in\u00e9ditas (algumas gravadas pelos pr\u00f3pria Mamonas) de turn\u00eas e shows\u00a0 e mostrar\u00e1 a traget\u00f3ria da banda at\u00e9 as paradas de sucesso nos anos 90.<br \/>\nO filme deve ser lan\u00e7ado apenas em 2010, mas neste final de semana uma pr\u00e9-estr\u00e9ia acontecer\u00e1 no mesmo lugar onde o vel\u00f3rio da banda foi realizado, o gin\u00e1sio Thomeoz\u00e3o, em Guarulhos &#8211; SP (cidade de origem do Mamonas).<\/p>\n<p>Kahns tamb\u00e9m est\u00e1 preparando um filme fict\u00edcio sobre a banda. &#8220;<strong>Mamonas, de Muvi<\/strong>&#8221;\u00a0 deve estrear nos cinemas tamb\u00e9m em 2010.<\/p>\n<p>E voc\u00ea, tamb\u00e9m era f\u00e3 do Mamonas Assassinas? Comenta a\u00ed!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eles tiveram uma carreira curta que acabou tragicamente em um acidente de avi\u00e3o que matou todos os membros da banda em 1996, mas n\u00e3o se pode negar que fizeram sucesso. O Mamonas Assassinas vendeu mais de dois milh\u00f5es de discos em seis meses e certamente deixaram o Brasil todo com gosto de quero mais&#8230; Para [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","webixso_pending_account_ids":""},"categories":[211],"tags":[640],"class_list":["post-2604","post","type-post","status-publish","format-standard","hentry","category-pipoca","tag-mamonas-assassinas"],"_links":{"self":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/2604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/comments?post=2604"}],"version-history":[{"count":0,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/2604\/revisions"}],"wp:attachment":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media?parent=2604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/categories?post=2604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/tags?post=2604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}