{"id":28926,"date":"2020-10-14T17:34:52","date_gmt":"2020-10-14T20:34:52","guid":{"rendered":"https:\/\/bestradiobrasil.com\/br\/?p=28926"},"modified":"2020-10-14T17:34:52","modified_gmt":"2020-10-14T20:34:52","slug":"turne-do-kiss-no-brasil-e-adiada-para-outubro-de-2021","status":"publish","type":"post","link":"https:\/\/bestradiobrasil.com\/br\/turne-do-kiss-no-brasil-e-adiada-para-outubro-de-2021\/","title":{"rendered":"Turn\u00ea do KISS no Brasil \u00e9 adiada para outubro de 2021"},"content":{"rendered":"<p>A\u00a0<strong>Mercury Concerts<\/strong>, respons\u00e1vel pela turn\u00ea da banda\u00a0<strong>KISS<\/strong>,\u00a0<strong>End Of The Road World\u00a0Tour<\/strong>, no Brasil, juntamente com a banda e seus representantes, anunciaram novas\u00a0datas para as apresenta\u00e7\u00f5es.<\/p>\n<p>Os organizadores informaram que n\u00e3o ser\u00e1 poss\u00edvel realizar a turn\u00ea em novembro\u00a0deste ano, tal como esperado, por conta do agravamento da pandemia do coronav\u00edrus,\u00a0que ainda persiste e que seguir\u00e3o a orienta\u00e7\u00e3o das autoridades p\u00fablicas\u00a0em manter as\u00a0restri\u00e7\u00f5es a aglomera\u00e7\u00f5es neste momento.<\/p>\n<p>As novas datas anunciadas para outubro de 2021 s\u00e3o:<\/p>\n<p><strong>S\u00e3o Paulo\/SP<\/strong>, dia <strong>16\/10\/2021<\/strong>, no <strong>Allianz Parque<\/strong><br \/>\n<strong>Ribeir\u00e3o Preto\/SP<\/strong>, dia <strong>17\/10\/2021<\/strong>, na <strong>Arena Eurobike<\/strong><br \/>\n<strong>Curitiba\/PR<\/strong>, dia <strong>19\/10\/2021<\/strong>, na <strong>Pedreira Paulo Leminski<\/strong><br \/>\n<strong>Porto Alegre\/RS<\/strong>, dia <strong>21\/10\/2021<\/strong>, <strong>Arena do Gr\u00eamio<\/strong><\/p>\n<p>Os organizadores ressaltam que todos os ingressos adquiridos ser\u00e3o v\u00e1lidos para as\u00a0respectivas novas datas, n\u00e3o havendo necessidade de troca\/substitui\u00e7\u00e3o de nenhum\u00a0ticket.<\/p>\n<p>Os shows em Bras\u00edlia e Uberl\u00e2ndia n\u00e3o foram reagendados e os consumidores que\u00a0adquiriram esses ingressos dever\u00e3o entrar em contato com as produtoras e ticketeiras\u00a0respons\u00e1veis, para mais informa\u00e7\u00f5es.<\/p>\n<p>Mais um aninho de espera pra esse grande show. Fazer o que, n\u00e9? S\u00f3 nos resta\u00a0esperar. =)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0Mercury Concerts, respons\u00e1vel pela turn\u00ea da banda\u00a0KISS,\u00a0End Of The Road World\u00a0Tour, no Brasil, juntamente com a banda e seus representantes, anunciaram novas\u00a0datas para as apresenta\u00e7\u00f5es. Os organizadores informaram que n\u00e3o ser\u00e1 poss\u00edvel realizar a turn\u00ea em novembro\u00a0deste ano, tal como esperado, por conta do agravamento da pandemia do coronav\u00edrus,\u00a0que ainda persiste e que seguir\u00e3o a [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":28927,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","webixso_pending_account_ids":""},"categories":[1],"tags":[13836,1024,13835],"class_list":["post-28926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-da-musica","tag-end-of-the-road-world-tour","tag-kiss","tag-mercury-concerts"],"_links":{"self":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/28926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/comments?post=28926"}],"version-history":[{"count":0,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/28926\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media\/28927"}],"wp:attachment":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media?parent=28926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/categories?post=28926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/tags?post=28926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}