{"id":31012,"date":"2024-07-16T10:59:56","date_gmt":"2024-07-16T13:59:56","guid":{"rendered":"https:\/\/bestradiobrasil.com\/br\/?p=31012"},"modified":"2024-07-16T10:59:56","modified_gmt":"2024-07-16T13:59:56","slug":"jbl-e-cerveja-combinacao-perfeita","status":"publish","type":"post","link":"https:\/\/bestradiobrasil.com\/br\/jbl-e-cerveja-combinacao-perfeita\/","title":{"rendered":"JBL e cerveja: combina\u00e7\u00e3o perfeita!"},"content":{"rendered":"<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div>\n<div class=\"pt-0.5 juice:pt-0\">\n<div class=\"gizmo-bot-avatar flex h-6 w-6 items-center justify-center overflow-hidden rounded-full juice:h-8 juice:w-8\">\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">A <strong>JBL<\/strong> est\u00e1 lan\u00e7ando uma nova linha de produtos que combina m\u00fasica e cerveja.<\/div>\n<div><\/div>\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">Com a ideia de proporcionar experi\u00eancias \u00fanicas, a marca pretende atrair amantes dos dois universos.<\/div>\n<div><\/div>\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">Essa iniciativa promete trazer inova\u00e7\u00e3o para os f\u00e3s de m\u00fasica e apreciadores de uma boa cerveja.<\/div>\n<div><\/div>\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">Fique atento para mais detalhes sobre essa parceria que promete agitar o mercado!<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A JBL est\u00e1 lan\u00e7ando uma nova linha de produtos que combina m\u00fasica e cerveja. Com a ideia de proporcionar experi\u00eancias \u00fanicas, a marca pretende atrair amantes dos dois universos. Essa iniciativa promete trazer inova\u00e7\u00e3o para os f\u00e3s de m\u00fasica e apreciadores de uma boa cerveja. Fique atento para mais detalhes sobre essa parceria que promete [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":31013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","webixso_pending_account_ids":""},"categories":[6],"tags":[2243,15886],"class_list":["post-31012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-cerveja","tag-jbl"],"_links":{"self":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/31012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/comments?post=31012"}],"version-history":[{"count":0,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts\/31012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media\/31013"}],"wp:attachment":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/media?parent=31012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/categories?post=31012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/tags?post=31012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}