{"id":17130,"count":1,"description":"","link":"https:\/\/bestradiobrasil.com\/br\/tag\/liz-meriwether\/","name":"Liz Meriwether","slug":"liz-meriwether","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/tags\/17130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bestradiobrasil.com\/br\/wp-json\/wp\/v2\/posts?tags=17130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}